﻿{"id":1433,"date":"2015-09-10T09:38:02","date_gmt":"2015-09-10T08:38:02","guid":{"rendered":"https:\/\/outletmandara.com\/blog\/?p=1433"},"modified":"2015-09-10T09:38:02","modified_gmt":"2015-09-10T08:38:02","slug":"el-aceite-arbol-del-te-y-los-piojos","status":"publish","type":"post","link":"https:\/\/www.outletmandara.com\/blog\/el-aceite-arbol-del-te-y-los-piojos\/","title":{"rendered":"El Aceite \u00e1rbol del t\u00e9 y los piojos"},"content":{"rendered":"<div>El aceite del \u00e1rbol del t\u00e9 es un derivado de un arbusto que se llama Melaleuca Alternifolia, que es oriundo de Australia.\u00a0Tiene propiedades antis\u00e9pticas, antif\u00fangicas, antibacterianas y cicatrizantes y se usa en la elaboraci\u00f3n de productos cosm\u00e9ticos.<\/div>\n<div>\n<p>El aceite esencial es un destilado de sus hojas, los abor\u00edgenes australianos ya utilizaban la planta del \u00e1rbol del t\u00e9, por sus m\u00faltiples beneficios para la salud.<\/p>\n<p>En est\u00e9tica es muy \u00fatil como potente desinfectante y para los tratamientos del acn\u00e9, eccemas, psoriasis o dermatitis at\u00f3pica.<\/p>\n<p>Lo podemos utilizar en problemas respiratorios, virales o bacterianos por su alto poder antibacteriano y antiv\u00edrico as\u00ed como por su capacidad inmunoestimulante (ayuda a nuestro organismo a incrementar las defensas en general).<\/p>\n<p>Entre sus muchas propiedades podemos tratar hemorroides, infecciones ginecol\u00f3gicas, par\u00e1sitos, conjuntivitis y orzuelos, mezcl\u00e1ndose con agua hervida o suero fisiol\u00f3gico para hacer lavados.<\/p>\n<p>Por su gran poder antimic\u00f3tico es imprescindible en cualquier gabinete donde se realicen manicuras y pedicuras, para poner las manos y pies a remojo, ya que evita la aparici\u00f3n de hongos evitando su proliferaci\u00f3n y contagio.<br \/>\nEste producto est\u00e1 indicado para usarse encima de u\u00f1as con micosis.<\/p>\n<p>En casos diagnosticados de c\u00e1ndida albicans es muy efectivo para curar el hongo y para evitar su aparici\u00f3n en personas propensas.<br \/>\nProporciona extraordinarios resultados es el la lucha contra los <strong>par\u00e1sitos externos, piojos<\/strong>; se usa puro cuando hay infestaci\u00f3n, untando bien la zona a tratar y tap\u00e1ndola con un pl\u00e1stico. A continuaci\u00f3n se deja actuar de 20 a 30 minutos para posteriormente lavar con un champ\u00fa al que habremos puesto unas gotas de esencia.<\/p>\n<p>Si nos centramos en el uso del aceite esencial para evitar los piojos podemos usarlo de varias formas:<\/p>\n<p><strong>1.<\/strong>\u00a0A\u00f1adir unas gotas de aceite del \u00e1rbol del t\u00e9 a tu\u00a0champ\u00fa habitual. Utilizarlo cada d\u00eda. No s\u00f3lo mantiene los piojos a distancia, tambi\u00e9n les impide volver. Notaras una mejora significativa dentro de una semana.<\/p>\n<p><strong>2.<\/strong>\u00a0Puedes mezclar los siguientes aceites: 5 gotas de aceite esencial de c\u00edtricos, 10 gotas de aceite esencial de eucalipto, 10 gotas de aceite de geranio, 20 gotas de aceite esencial de lavanda, 20 gotas de aceite esencial de romero, 5 gotas de aceite del \u00e1rbol del t\u00e9, 100ml de aceite vegetal. Aplicar esta mezcla al cabello y cuero cabelludo. Cubrirlo. Dejar actuar durante dos o tres horas antes de lavar. Eso permite matar a los piojos.<\/p>\n<p><strong>3.<\/strong>\u00a0A\u00f1ade 25 gotas de aceite del \u00e1rbol del t\u00e9 a medio litro de agua destilada o agua de manantial. Frotar esto en el cabello y cuero cabelludo tres veces al d\u00eda. Peinar con un peine de dientes finos o un peine para piojos. El aceite del \u00e1rbol del t\u00e9 act\u00faa como desinfectante.<\/p>\n<p>En conclusi\u00f3n para prevenir los temidos piojos, usando el aceite de alguna de estar 3 formas, evitamos que nuestros peque\u00f1os sean objetivo de estos molestos bichitos, y si tenemos que luchar contra ellos, este aceite nos ayuda a eliminarlos de manera segura.<\/p><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El aceite del \u00e1rbol del t\u00e9 es un derivado de un arbusto que se llama Melaleuca Alternifolia, que es oriundo de Australia.\u00a0Tiene propiedades antis\u00e9pticas, antif\u00fangicas, &#8230; <a title=\"El Aceite \u00e1rbol del t\u00e9 y los piojos\" class=\"read-more\" href=\"https:\/\/www.outletmandara.com\/blog\/el-aceite-arbol-del-te-y-los-piojos\/\" aria-label=\"M\u00e1s en El Aceite \u00e1rbol del t\u00e9 y los piojos\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":1434,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rank_math_lock_modified_date":false,"footnotes":""},"categories":[1,47],"tags":[],"_links":{"self":[{"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/posts\/1433"}],"collection":[{"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/comments?post=1433"}],"version-history":[{"count":1,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/posts\/1433\/revisions"}],"predecessor-version":[{"id":1435,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/posts\/1433\/revisions\/1435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/media\/1434"}],"wp:attachment":[{"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/media?parent=1433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/categories?post=1433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/tags?post=1433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}