﻿{"id":126,"date":"2012-01-24T12:04:38","date_gmt":"2012-01-24T11:04:38","guid":{"rendered":"https:\/\/outletmandara.com\/blog\/?p=126"},"modified":"2017-10-18T11:57:28","modified_gmt":"2017-10-18T10:57:28","slug":"receta-balsamo-humedecer-labios","status":"publish","type":"post","link":"https:\/\/www.outletmandara.com\/blog\/receta-balsamo-humedecer-labios\/","title":{"rendered":"Receta para b\u00e1lsamo para humedecer los labios"},"content":{"rendered":"<p>Con este <strong>b\u00e1lsamo para humedecer los labios<\/strong> puedes mantener tus <strong>labios brillantes, sanos y h\u00famedos<\/strong> todo el a\u00f1o, a\u00fan en los meses de temperaturas extremas. Es un poco m\u00e1s complicada que otras recetas caseras que hemos recogido en <a title=\"Belleza y Salud\" href=\"https:\/\/bellezaysalud.outletmandara.com\">Belleza y Salud<\/a>, pero merece la pena para tus labios.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-2472 size-full\" src=\"https:\/\/www.outletmandara.com\/blog\/wp-content\/uploads\/2012\/01\/labios-humedos.jpg\" alt=\"labios bonitos\" width=\"965\" height=\"1448\" srcset=\"https:\/\/www.outletmandara.com\/blog\/wp-content\/uploads\/2012\/01\/labios-humedos.jpg 965w, https:\/\/www.outletmandara.com\/blog\/wp-content\/uploads\/2012\/01\/labios-humedos-200x300.jpg 200w, https:\/\/www.outletmandara.com\/blog\/wp-content\/uploads\/2012\/01\/labios-humedos-768x1152.jpg 768w, https:\/\/www.outletmandara.com\/blog\/wp-content\/uploads\/2012\/01\/labios-humedos-682x1024.jpg 682w\" sizes=\"(max-width: 965px) 100vw, 965px\" \/><\/p>\n<h2><strong>Materiales<\/strong><\/h2>\n<ul>\n<li>2 cucharaditas (10 gramos) de <strong>cera de abejas<\/strong> (podr\u00e1s conseguirla\u00a0<a href=\"https:\/\/www.outletmandara.com\/cera-de-abejas-virgen-500g\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>)<\/li>\n<li>5 onzas (70 gramos) de <strong>manteca o mantequilla de cacao<\/strong><\/li>\n<li>2 cucharaditas de <strong>aceite de oliva<\/strong><\/li>\n<\/ul>\n<h3>Opcional<\/h3>\n<ul>\n<li>10 gotas de <strong>vainilla<\/strong> (tendr\u00e1 olor a vainilla) o 10 gotas de aceite esencial de <strong>naranja<\/strong> o 10 gotas de <strong>jarabe<\/strong> de alg\u00fan dulce de la secci\u00f3n de hornear o de dulces del supermercado. Esto <strong>le da sabor y olor<\/strong> y dependiendo de lo que se use color.<\/li>\n<\/ul>\n<p>Otra opci\u00f3n es poner un poquito de un <strong>l\u00e1piz de labios para darle un poco de color<\/strong>. No usar color vegetal de cocinar porque mancha los labios.<\/p>\n<p>Cuanto m\u00e1s aceite uses menos firme ser\u00e1 el protector labial, en climas calientes es conveniente usar menos aceite para que no se derrita con facilidad.<\/p>\n<h2><strong>Utensilios<\/strong><\/h2>\n<ul>\n<li>Un frasco peque\u00f1o, limpio y seco o dos tubos de l\u00e1piz labial vac\u00edos.<\/li>\n<li>Un pirex u otra cacerola para poner a ba\u00f1o Maria.<\/li>\n<li>Una sart\u00e9n o olla para hacer el ba\u00f1o Maria.<\/li>\n<\/ul>\n<h2><strong>Preparaci\u00f3n<\/strong><\/h2>\n<ol>\n<li>Poner agua en la olla y sobre esta poner el p\u00edrex con la cera y la mantequilla de cacao, hasta que se derritan. Si usas l\u00e1piz labial, ponerlo en esta mezcla hasta que se derrita.<\/li>\n<li>A\u00f1adir el resto de los ingredientes, mover bien.<\/li>\n<li>Pasar la mezcla al frasco y dejar enfriar.<\/li>\n<\/ol>\n<p>Para mantener los<strong> labios humedecidos<\/strong> especialmente en meses de fr\u00edo los siguientes ingredientes son muy efectivos y <strong>puedes modificar la receta<\/strong> intercambiando ingredientes:<\/p>\n<ul>\n<li>Manteca de karite (shea butter)<\/li>\n<li>Gotas de vitamina E<\/li>\n<li>Gotas de aceite de germen de trigo<\/li>\n<li>Aceite esencial de semilla de zanahoria<\/li>\n<\/ul>\n<h3>Nota<\/h3>\n<p>No tires ning\u00fan desperdicio de esta receta a las tuberias porque se pone dura y puede obstruirla. L\u00edmpiala con papel toalla y t\u00edrala en la basura.<\/p>\n<p>Si te animas a hacerla, y te gusta, no dudes en comentarnos tu experiencia. Y si resulta demasiado laboriosa para ti, pues tienes demasiado trabajo, echa un vistazo a estos <a href=\"https:\/\/www.outletmandara.com\/blog\/consejos-de-belleza-para-mujeres-ocupadas\/\" target=\"_blank\" rel=\"noopener\">consejos de belleza para mujeres ocupadas<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con este b\u00e1lsamo humedecedor de labios puedes mantener tus labios brillantes, sanos y h\u00famedos todo el a\u00f1o, a\u00fan en los meses de temperaturas extremas.<\/p>\n","protected":false},"author":6,"featured_media":2471,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rank_math_lock_modified_date":false,"footnotes":""},"categories":[24],"tags":[141,140],"_links":{"self":[{"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/posts\/126"}],"collection":[{"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/comments?post=126"}],"version-history":[{"count":11,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/posts\/126\/revisions"}],"predecessor-version":[{"id":2470,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/posts\/126\/revisions\/2470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/media\/2471"}],"wp:attachment":[{"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/media?parent=126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/categories?post=126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/tags?post=126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}