﻿{"id":1080,"date":"2015-03-17T12:06:20","date_gmt":"2015-03-17T11:06:20","guid":{"rendered":"https:\/\/outletmandara.com\/blog\/?p=1080"},"modified":"2015-04-28T12:00:36","modified_gmt":"2015-04-28T11:00:36","slug":"las-cremas-cosmeticas-no-sirven-para-todo","status":"publish","type":"post","link":"https:\/\/www.outletmandara.com\/blog\/las-cremas-cosmeticas-no-sirven-para-todo\/","title":{"rendered":"Las cremas cosm\u00e9ticas no sirven para todo."},"content":{"rendered":"<p>Acn\u00e9, psoriasis, eccemas, hongos, existen una serie de enfermedades cut\u00e1neas que son importantes a tener en cuenta, sobre todo a la hora de tratar o de buscar una crema o tratamiento que las ayude a mejorar y a que no empeoren.<\/p>\n<p>Ana Mandara no tiene una l\u00ednea cosm\u00e9tica pensada para este tipo de problema en la piel, porque consideramos que son problemas que tienen que ser tratados por un dermat\u00f3logo, por lo que su cuidado va a cargo de cremas medicinales y medicamentos.<\/p>\n<p>El acn\u00e9, la psoriasis\u00a0y\u00a0los hongos son infecciones bacterianas, son las dermatosis m\u00e1s comunes y hablamos de infecciones, por lo que las cremas cosm\u00e9ticas de uso est\u00e9tico ya no tienen aqu\u00ed una funci\u00f3n de cuidado est\u00e9tico, si no que tienen que tratarse con medicamentos.<\/p>\n<p>Un m\u00e9dico o dermat\u00f3logo es quien\u00a0tiene que diagnosticar el por qu\u00e9 del acn\u00e9 y tratarlo o con cremas antibacterianas o con medicamentos hormonales.<\/p>\n<p>Nosotros lo que podemos ofrecer en estos casos son productos de limpieza y t\u00f3nicos para desinfectar la superficie de la piel y evitar la proliferaci\u00f3n de m\u00e1s bacterias.<\/p>\n<p>La psoriasis se cree que es bacteriana, pero realmente es la gran desconocida, no se contagia, no da molestias f\u00edsicas importantes pero visualmente es desagradable, se han hecho descubrimientos que afirman que los estados de \u00e1nimo, el calor o la humedad pueden agravar\u00a0su estado o mitigarlo, nosotros tampoco tratamos este problema con cosm\u00e9tica, lo \u00fanico que ofrecemos es una buena crema hidratante para la piel, para mantener su humedad, pero el tratamiento le corresponde a un m\u00e9dico.<\/p>\n<p>Queremos lo mejor para ti y para tu piel.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-1081\" src=\"https:\/\/outletmandara.com\/blog\/wp-content\/uploads\/2015\/03\/blog-ana-mandara.jpg\" alt=\"blog ana mandara\" width=\"620\" height=\"416\" srcset=\"https:\/\/www.outletmandara.com\/blog\/wp-content\/uploads\/2015\/03\/blog-ana-mandara.jpg 620w, https:\/\/www.outletmandara.com\/blog\/wp-content\/uploads\/2015\/03\/blog-ana-mandara-300x201.jpg 300w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acn\u00e9, psoriasis, eccemas, hongos, existen una serie de enfermedades cut\u00e1neas que son importantes a tener en cuenta, sobre todo a la hora de tratar o &#8230; <a title=\"Las cremas cosm\u00e9ticas no sirven para todo.\" class=\"read-more\" href=\"https:\/\/www.outletmandara.com\/blog\/las-cremas-cosmeticas-no-sirven-para-todo\/\" aria-label=\"M\u00e1s en Las cremas cosm\u00e9ticas no sirven para todo.\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":1105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rank_math_lock_modified_date":false,"footnotes":""},"categories":[1,51],"tags":[],"_links":{"self":[{"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/posts\/1080"}],"collection":[{"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/comments?post=1080"}],"version-history":[{"count":6,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/posts\/1080\/revisions"}],"predecessor-version":[{"id":1285,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/posts\/1080\/revisions\/1285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/media\/1105"}],"wp:attachment":[{"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/media?parent=1080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/categories?post=1080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.outletmandara.com\/blog\/wp-json\/wp\/v2\/tags?post=1080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}